{"id":2253,"date":"2025-01-14T09:02:29","date_gmt":"2025-01-14T09:02:29","guid":{"rendered":"https:\/\/ecenglish.com\/?page_id=2253"},"modified":"2026-07-24T14:15:10","modified_gmt":"2026-07-24T14:15:10","slug":"ec-cambridge-arrivo-primo-giorno","status":"publish","type":"page","link":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/","title":{"rendered":"EC Cambridge arrivo primo giorno"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--xs);padding-bottom:var(--wp--preset--spacing--xs)\">\n<div class=\"wp-block-group alignwide has-global-padding is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-a81b9b62 wp-block-group-is-layout-constrained\"><div class=\"yoast-breadcrumbs\"><span><span><a href=\"https:\/\/ecenglish.com\/it\/\">Home<\/a><\/span> <svg viewBox=\"0 0 4 6\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M.863 1.78a.659.659 0 0 1 0-.937.673.673 0 0 1 .946 0l1.976 1.96a.727.727 0 0 1 0 1.032l-1.97 1.953a.673.673 0 0 1-1.091-.215.659.659 0 0 1 .145-.723l1.545-1.531L.863 1.78Z\"\/><\/svg> <span><a href=\"https:\/\/ecenglish.com\/it\/scuole\/\">Scuole di lingua inglese all&#8217;estero \u00a0\u00a0<\/a><\/span> <svg viewBox=\"0 0 4 6\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M.863 1.78a.659.659 0 0 1 0-.937.673.673 0 0 1 .946 0l1.976 1.96a.727.727 0 0 1 0 1.032l-1.97 1.953a.673.673 0 0 1-1.091-.215.659.659 0 0 1 .145-.723l1.545-1.531L.863 1.78Z\"\/><\/svg> <span><a href=\"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/\">Impara l&#8217;inglese nel Regno Unito<\/a><\/span> <svg viewBox=\"0 0 4 6\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M.863 1.78a.659.659 0 0 1 0-.937.673.673 0 0 1 .946 0l1.976 1.96a.727.727 0 0 1 0 1.032l-1.97 1.953a.673.673 0 0 1-1.091-.215.659.659 0 0 1 .145-.723l1.545-1.531L.863 1.78Z\"\/><\/svg> <span class=\"breadcrumb_last\" aria-current=\"page\">EC Cambridge arrivo primo giorno<\/span><\/span><\/div><\/div>\n<\/div>\n\n\n\n\t\t\n<div class=\"wp-block-intro-slider alignfull layout-container wp-block-ec-intro-slider\">\n\t<div class=\"container\">\n\t\t<div class=\"intro-slider-wrapper\">\n\t\t\t<div class=\"swiper intro-slider\" data-slides-count=\"1\">\n\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\n\n\n\n<div class=\"swiper-slide wp-block-intro-slider-slide\">\n\t<div class=\"slide-content\">\n\t\t\n\n\n\t<h1 style=\"margin-top:var(--wp--preset--spacing--xs);margin-bottom:var(--wp--preset--spacing--xs)\" class=\"wp-block-ec-html-wrapper\">\n\t\n\n<p class=\"has-ec-white-color has-text-color has-link-color content-type-h4 wp-elements-30d4839b2dbc2ee7ddf82a63a82e1b85 wp-block-paragraph\">EC Cambridge<\/p>\n\n\n\n<p class=\"has-ec-white-color has-text-color has-link-color content-type-h1 wp-elements-60041a2d787ddbbca4230f4f901e212f wp-block-paragraph\">Pre-arrivo al primo giorno<\/p>\n\n\t<\/h1>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-container-core-buttons-is-layout-ab3d7b5f wp-block-buttons-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--l)\">\n<div class=\"wp-block-button is-style-outline has-primary-background-hover-color is-style-outline--1\"><a class=\"wp-block-button__link has-ec-white-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-guida-di-viaggio-attivita\/\" style=\"border-radius:50px\" target=\"_blank\" rel=\"noreferrer noopener\">guida di viaggio<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline has-primary-background-hover-color is-style-outline--2\"><a class=\"wp-block-button__link has-ec-white-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/imparare-inglese-a-cambridge\/\" style=\"border-radius:50px\">panoramica di ec Cambridge<\/a><\/div>\n\n\n\n\n<div style=\"margin-top:var(--wp--preset--spacing--l);margin-bottom:var(--wp--preset--spacing--l)\" class=\"wp-block-button wp-block-intro-button-pdf is-style-fill has-ec-white-color has-digital-blue-background-color has-text-color has-background has-link-color has-icon has-icon-download icon-position-left wp-block-ec-intro-button-pdf\" >\n\t<a href=\"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/4\/pdf\/2253.pdf?v=1784816200\" download=\"EC Cambridge arrivo primo giorno.pdf\" target=\"_blank\" class=\"\n\twp-block-button__link\n\thas-ec-white-color\n\thas-digital-blue-background-color\n\thas-text-color\n\thas-background\n\thas-link-color\n\twp-element-button\n\ticon-position-left\">\n\t\t\t\t\t<picture class=\"icon-wrap has-icon has-icon-download\">\n\t\t\t\t<svg width=\"20\" height=\"19\" viewbox=\"0 0 20 19\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M8.687 14.5928C8.5956 14.5005 8.48681 14.4272 8.36691 14.3772C8.24702 14.3272 8.1184 14.3014 7.9885 14.3014C7.8586 14.3014 7.72998 14.3272 7.61009 14.3772C7.49019 14.4272 7.3814 14.5005 7.29 14.5928C7.10466 14.78 7.0007 15.0328 7.0007 15.2963C7.0007 15.5597 7.10466 15.8125 7.29 15.9998L9.254 17.9798C9.35461 18.0814 9.47438 18.1621 9.60638 18.2172C9.73837 18.2723 9.87998 18.3006 10.023 18.3006C10.166 18.3006 10.3076 18.2723 10.4396 18.2172C10.5716 18.1621 10.6914 18.0814 10.792 17.9798L12.711 16.0468C12.8966 15.8595 13.0008 15.6065 13.0008 15.3428C13.0008 15.0791 12.8966 14.8261 12.711 14.6388C12.6196 14.5463 12.5107 14.4729 12.3907 14.4228C12.2708 14.3727 12.142 14.3469 12.012 14.3469C11.882 14.3469 11.7532 14.3727 11.6333 14.4228C11.5133 14.4729 11.4044 14.5463 11.313 14.6388L10.023 15.9388L8.687 14.5928Z\" fill=\"currentColor\" \/>\n<path d=\"M11.001 17.2938L11 7.30678C11 6.75178 10.552 6.30078 10 6.30078C9.448 6.30078 9 6.75078 9 7.30778L9.001 17.2948C9.001 17.8498 9.449 18.3008 10.001 18.3008C10.553 18.3008 11.001 17.8508 11.001 17.2938Z\" fill=\"currentColor\" \/><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M5.938 2.78078C5.68111 2.73908 5.42125 2.71835 5.161 2.71878C2.356 2.71878 0 4.92078 0 7.79878C0 10.7098 2.385 13.3008 5.1 13.3008H7.981V11.3078H5.1C3.443 11.3078 1.985 9.64478 1.985 7.79978C1.985 6.02178 3.454 4.71278 5.089 4.71278H5.101C5.49 4.71278 5.787 4.76278 6.071 4.86278L6.241 4.92578C6.846 5.17378 7.116 4.67978 7.116 4.67978L7.266 4.41278C7.996 3.06578 9.467 2.31678 10.982 2.29278C11.9871 2.30282 12.9543 2.6782 13.703 3.3489C14.4517 4.0196 14.9309 4.93979 15.051 5.93778L15.097 6.27778C15.097 6.27778 15.168 6.80278 15.762 6.80278C15.775 6.80278 15.774 6.80778 15.785 6.80778H16.039C17.175 6.80778 18.015 7.76678 18.015 8.96578C18.015 10.1728 17.028 11.3078 15.945 11.3078H11.981V13.3008H15.945C18.105 13.3008 20 11.2558 20 8.96578C20 6.96578 18.688 5.30278 16.862 4.89178C16.155 2.18478 13.809 0.339781 10.976 0.300781C9.001 0.320781 7.075 1.20078 5.938 2.78078Z\" fill=\"currentColor\" \/>\n<\/svg>\n\t\t\t<\/picture>\n\t\t\t\t<span class=\"button-text\">\n\t\t\tGET pdf\t\t<\/span>\n\t<\/a>\n<\/div>\n<\/div>\n\n\t<\/div>\n\t\t\t<img width=\"806\" height=\"537\" src=\"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Punting-Tour-with-friends-in-Cambridge.jpg\" class=\"bg-img intro-slide-bg-img skip-lazy\" alt=\"\"   data-skip-lazy=\"1\" loading=\"eager\" decoding=\"sync\" fetchpriority=\"high\" \/>\t\t<div class=\"bg-overlay\"><\/div>\n<\/div>\n\n\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"swiper-pagination-wrap\">\n\t\t\t\t\t<div class=\"swiper-pagination\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination--btn-autoplay\" role=\"button\" aria-label=\"Autoplay Riproduzione\/Pausa\">\n\t\t\t\t\t\t<svg class=\"pause\" width=\"8\" height=\"11\" viewBox=\"0 0 8 11\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t<path\n\t\t\t\t\t\t\t\td=\"M1.08366 0.0585938C1.24695 0.0586153 1.40455 0.118564 1.52657 0.22707C1.6486 0.335577 1.72655 0.485093 1.74566 0.64726L1.75033 0.72526V10.0586C1.75014 10.2285 1.68507 10.3919 1.56843 10.5155C1.45178 10.6391 1.29236 10.7134 1.12273 10.7234C0.953101 10.7333 0.786073 10.6781 0.655771 10.5691C0.525469 10.46 0.441728 10.3053 0.421659 10.1366L0.416992 10.0586V0.72526C0.416992 0.548449 0.48723 0.37888 0.612254 0.253856C0.737279 0.128832 0.906848 0.0585937 1.08366 0.0585938ZM6.41699 0.0585938C6.58028 0.0586153 6.73788 0.118564 6.85991 0.22707C6.98193 0.335577 7.05989 0.485093 7.07899 0.64726L7.08366 0.72526V10.0586C7.08347 10.2285 7.01841 10.3919 6.90176 10.5155C6.78511 10.6391 6.62569 10.7134 6.45606 10.7234C6.28643 10.7333 6.11941 10.6781 5.9891 10.5691C5.8588 10.46 5.77506 10.3053 5.75499 10.1366L5.75033 10.0586V0.72526C5.75033 0.548449 5.82056 0.37888 5.94559 0.253856C6.07061 0.128832 6.24018 0.0585937 6.41699 0.0585938Z\"\n\t\t\t\t\t\t\t\tfill=\"white\"\/>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t<svg class=\"play\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n\t\t\t\t\t\t\t\t\td=\"M3.45425 15.5219C2.02125 16.3639 0.859253 15.7019 0.859253 14.0399V1.96289C0.859253 0.299891 2.01725 -0.365109 3.45425 0.478891L14.5373 6.98889C15.4883 7.54789 15.4953 8.44889 14.5373 9.01189L3.45425 15.5219Z\"\n\t\t\t\t\t\t\t\t\tfill=\"#9A9C9E\"\/>\n\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div role=\"button\" aria-label=\"Slide Precedente\" class=\"swiper-nav-btn swiper-button-prev\">\n\t\t\t\t\t<svg width=\"34\" height=\"35\" viewBox=\"0 0 34 35\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n\t\t\t\t\t\t\t\td=\"M0.333411 17.4998C0.33341 8.29509 7.79533 0.83317 17.0001 0.833169C26.2048 0.833169 33.6667 8.29509 33.6667 17.4998C33.6667 26.7046 26.2048 34.1665 17.0001 34.1665C7.79533 34.1665 0.333412 26.7046 0.333411 17.4998ZM20.2063 21.8735C20.1221 21.6723 19.9988 21.4897 19.8434 21.3365L15.9651 17.4915L19.8284 13.6632C19.9838 13.51 20.1071 13.3274 20.1913 13.1262C20.2755 12.9249 20.3189 12.7089 20.3189 12.4907C20.3189 12.2725 20.2755 12.0565 20.1913 11.8552C20.1071 11.6539 19.9838 11.4714 19.8284 11.3182C19.5133 11.0067 19.0881 10.8321 18.6451 10.8321C18.202 10.8321 17.7768 11.0067 17.4617 11.3182L12.5367 16.2015C12.3664 16.3704 12.2312 16.5714 12.139 16.7928C12.0467 17.0142 11.9992 17.2517 11.9992 17.4915C11.9992 17.7314 12.0467 17.9689 12.139 18.1903C12.2312 18.4117 12.3664 18.6126 12.5367 18.7815L17.4784 23.6815C17.7934 23.9925 18.2183 24.1668 18.6609 24.1668C19.1036 24.1668 19.5284 23.9925 19.8434 23.6815C19.9988 23.5283 20.1221 23.3458 20.2063 23.1445C20.2905 22.9432 20.3339 22.7272 20.3339 22.509C20.3339 22.2908 20.2905 22.0748 20.2063 21.8735Z\"\n\t\t\t\t\t\t\t\tfill=\"#FEFCF5\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div role=\"button\" aria-label=\"Slide Successiva\" class=\"swiper-nav-btn swiper-button-next\">\n\t\t\t\t\t<svg width=\"34\" height=\"35\" viewBox=\"0 0 34 35\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\"\n\t\t\t\t\t\t\t\td=\"M33.6666 17.5002C33.6666 26.7049 26.2047 34.1668 16.9999 34.1668C7.79517 34.1668 0.333252 26.7049 0.333252 17.5002C0.333252 8.29542 7.79517 0.833496 16.9999 0.833496C26.2047 0.833496 33.6666 8.29542 33.6666 17.5002ZM13.7937 13.1265C13.8779 13.3277 14.0012 13.5103 14.1566 13.6635L18.0349 17.5085L14.1716 21.3368C14.0162 21.49 13.8929 21.6726 13.8087 21.8738C13.7245 22.0751 13.6811 22.2911 13.6811 22.5093C13.6811 22.7275 13.7245 22.9435 13.8087 23.1448C13.8929 23.3461 14.0162 23.5286 14.1716 23.6818C14.4867 23.9933 14.9119 24.1679 15.3549 24.1679C15.798 24.1679 16.2232 23.9933 16.5383 23.6818L21.4633 18.7985C21.6336 18.6296 21.7688 18.4286 21.861 18.2072C21.9533 17.9858 22.0008 17.7483 22.0008 17.5085C22.0008 17.2686 21.9533 17.0311 21.861 16.8097C21.7688 16.5883 21.6336 16.3874 21.4633 16.2185L16.5216 11.3185C16.2066 11.0075 15.7817 10.8332 15.3391 10.8332C14.8964 10.8332 14.4716 11.0075 14.1566 11.3185C14.0012 11.4717 13.8779 11.6542 13.7937 11.8555C13.7095 12.0568 13.6661 12.2728 13.6661 12.491C13.6661 12.7092 13.7095 12.9252 13.7937 13.1265Z\"\n\t\t\t\t\t\t\t\tfill=\"#FEFCF5\"\/>\n\t\t\t\t\t<\/svg>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<a href=\"#\"\n\t\t\t\ttarget=\"http:\/\/_self\"\n\t\t\t\ttitle=\"\"\n\t\t\t\tclass=\"trustpilot-widget\">\n\t\t\t\t\t\t\t\t\t<div class=\"trustpilot-widget__label\">Excellent<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"trustpilot-widget__stars\">\t\t<div class=\"stars\" data-start=\"5\">\n\t\t\t\t\t\t\t<svg class=\"full\" width=\"22\" height=\"23\" viewBox=\"0 0 22 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<rect width=\"22\" height=\"22\" transform=\"translate(0 0.03125)\" fill=\"#00B67A\"\/>\n\t\t\t\t\t<path d=\"M11.0008 15.0748L14.3466 14.1789L15.7445 18.7311L11.0008 15.0748ZM18.7008 9.1908H12.8112L11.0008 3.33105L9.19037 9.1908H3.30078L8.06745 12.8229L6.25703 18.6826L11.0237 15.0506L13.957 12.8229L18.7008 9.1908Z\"\n\t\t\t\t\t\t  fill=\"white\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<svg class=\"full\" width=\"22\" height=\"23\" viewBox=\"0 0 22 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<rect width=\"22\" height=\"22\" transform=\"translate(0 0.03125)\" fill=\"#00B67A\"\/>\n\t\t\t\t\t<path d=\"M11.0008 15.0748L14.3466 14.1789L15.7445 18.7311L11.0008 15.0748ZM18.7008 9.1908H12.8112L11.0008 3.33105L9.19037 9.1908H3.30078L8.06745 12.8229L6.25703 18.6826L11.0237 15.0506L13.957 12.8229L18.7008 9.1908Z\"\n\t\t\t\t\t\t  fill=\"white\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<svg class=\"full\" width=\"22\" height=\"23\" viewBox=\"0 0 22 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<rect width=\"22\" height=\"22\" transform=\"translate(0 0.03125)\" fill=\"#00B67A\"\/>\n\t\t\t\t\t<path d=\"M11.0008 15.0748L14.3466 14.1789L15.7445 18.7311L11.0008 15.0748ZM18.7008 9.1908H12.8112L11.0008 3.33105L9.19037 9.1908H3.30078L8.06745 12.8229L6.25703 18.6826L11.0237 15.0506L13.957 12.8229L18.7008 9.1908Z\"\n\t\t\t\t\t\t  fill=\"white\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<svg class=\"full\" width=\"22\" height=\"23\" viewBox=\"0 0 22 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<rect width=\"22\" height=\"22\" transform=\"translate(0 0.03125)\" fill=\"#00B67A\"\/>\n\t\t\t\t\t<path d=\"M11.0008 15.0748L14.3466 14.1789L15.7445 18.7311L11.0008 15.0748ZM18.7008 9.1908H12.8112L11.0008 3.33105L9.19037 9.1908H3.30078L8.06745 12.8229L6.25703 18.6826L11.0237 15.0506L13.957 12.8229L18.7008 9.1908Z\"\n\t\t\t\t\t\t  fill=\"white\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t<svg class=\"full\" width=\"22\" height=\"23\" viewBox=\"0 0 22 23\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<rect width=\"22\" height=\"22\" transform=\"translate(0 0.03125)\" fill=\"#00B67A\"\/>\n\t\t\t\t\t<path d=\"M11.0008 15.0748L14.3466 14.1789L15.7445 18.7311L11.0008 15.0748ZM18.7008 9.1908H12.8112L11.0008 3.33105L9.19037 9.1908H3.30078L8.06745 12.8229L6.25703 18.6826L11.0237 15.0506L13.957 12.8229L18.7008 9.1908Z\"\n\t\t\t\t\t\t  fill=\"white\"\/>\n\t\t\t\t<\/svg>\n\t\t\t\n\t\t\t<!-- Render half star if applicable -->\n\t\t\t\n\t\t\t<!-- Render empty stars -->\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"trustpilot-widget__logo\"><img width=\"80\" height=\"21\" src=\"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/trustpilot.svg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" decoding=\"async\" fetchpriority=\"low\" \/><\/div>\n\t\t\t\t\t\t\t<\/a>\n\t\t\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--l);margin-bottom:var(--wp--preset--spacing--l);padding-top:0;padding-bottom:0\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"padding-top:0;padding-bottom:0\">Preparati per la tua esperienza EC Cambridge<\/h2>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\">Informazioni essenziali per prepararsi al viaggio a Cambridge<\/h4>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--l);margin-bottom:var(--wp--preset--spacing--l)\">\n<div style=\"margin-top:var(--wp--preset--spacing--m)\" class=\"ec-anchor-navigation alignwide wp-block-ec-anchor-navigation\" data-scan=\"h2\">\n\t<nav>\n\t\t<ul>\n\t\t\t<li class=\"active\"><a href=\"#\">Calculating<\/a><\/li>\n\t\t\t<li><a href=\"#\">Headings<\/a><\/li>\n\t\t\t<li><a href=\"#\">&#8230;<\/a><\/li>\n\t\t<\/ul>\n\t<\/nav>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-style-alignfull-side-margins has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--m);padding-bottom:var(--wp--preset--spacing--m)\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center mobile-gap-4 mobile-column-gap-4 tablet-gap-5 tablet-column-gap-5 tablet-vertical-alignment-start is-layout-flex wp-container-core-columns-is-layout-4840dda6 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-column is-vertically-aligned-center is-style-sticky-tablet mobile-order--1 text-content is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\" style=\"margin-top:var(--wp--preset--spacing--xs);margin-bottom:var(--wp--preset--spacing--xs);padding-top:0;padding-bottom:0\">Prima dell&#8217;arrivo<\/h2>\n\n\n\n<h3 class=\"wp-block-heading has-primary-color has-text-color has-link-color wp-elements-05fed57ab82d9b90d29134ad0e325d5b\" style=\"margin-top:var(--wp--preset--spacing--xs);margin-bottom:var(--wp--preset--spacing--xs);padding-top:0;padding-bottom:0\">MyEC<\/h3>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Che cos&#8217;\u00e8 MyEC?<\/p>\n\n\n\n<p style=\"margin-top:var(--wp--preset--spacing--m)\" class=\"wp-block-paragraph\">MyEC \u00e8 uno strumento di studio personalizzato e un potente compagno di apprendimento per tutto il percorso EC. Offre anche informazioni sul centro EC, sull&#8217;alloggio e sulla vita nella destinazione scelta.<\/p>\n\n\n\n<div class=\"wp-block-columns mobile-gap-3 mobile-column-gap-3 is-layout-flex wp-container-core-columns-is-layout-0666dacc wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--m)\">\n<div class=\"wp-block-column mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Il test di ingresso online<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Per aiutarci a collocarvi nel livello giusto quando iniziate a studiare con noi, dovete completare il test di posizionamento online prima di arrivare a scuola.<\/li>\n\n\n\n<li>Se non completate questo test prima del primo giorno, potreste perdere alcune delle attivit\u00e0 del primo giorno e\/o delle ore di lezione, poich\u00e9 il test deve essere completato prima dell&#8217;inizio delle lezioni.<\/li>\n\n\n\n<li>Il test di ingresso online si concentra su lettura, scrittura e uso dell&#8217;inglese (grammatica e vocabolario) e consiste in 66 domande.<\/li>\n\n\n\n<li>Il livello di conversazione sar\u00e0 valutato il primo giorno di scuola.<\/li>\n\n\n\n<li class=\"has-link-color wp-elements-eb03cd22b199023b2344a66b4e57831e\">Per le istruzioni su come completare il test di ingresso online, consultare la sezione<a href=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/Preparing-for-your-Arrival.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Preparazione all&#8217;arrivo\u00a0\u00a0<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Quando posso accedere a MyEC?<\/p>\n\n\n\n<p class=\"has-link-color wp-elements-df1bafc912c571fc586b62e845824272 wp-block-paragraph\">Potrete accedere a MyEC non appena riceverete la conferma della prenotazione. Iniziate ad accedere qui:<a href=\"http:\/\/signin.ecenglish.com\/student\">https:\/\/signin.ecenglish.com\/student<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-ec-grey-4-color has-alpha-channel-opacity has-ec-grey-4-background-color has-background\"\/>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Cos&#8217;altro devo fare su MyEC prima del mio arrivo?<\/p>\n\n\n\n<ol class=\"wp-block-list is-style-default\">\n<li>Accedete a una banca di materiali di studio per iniziare a imparare prima ancora di uscire di casa<\/li>\n\n\n\n<li>Completate il vostro modulo di informazioni personali importanti<\/li>\n\n\n\n<li>Completate il vostro modulo di analisi dei bisogni<\/li>\n\n\n\n<li>Completate il vostro test di ingresso<\/li>\n\n\n\n<li>Compilate il sondaggio pre-arrivo<\/li>\n<\/ol>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-style-sticky-tablet mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.3%\">\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img width=\"1118\" height=\"1080\" fetchpriority=\"low\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/01\/My-EC-App-Student-5.jpg\" alt=\"\" class=\"wp-image-4907\" style=\"border-radius:1rem\" srcset=\"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/My-EC-App-Student-5.jpg 1118w, https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/My-EC-App-Student-5-300x290.jpg 300w, https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/My-EC-App-Student-5-1024x989.jpg 1024w, https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/My-EC-App-Student-5-768x742.jpg 768w\" sizes=\"auto, (max-width: 1118px) 100vw, 1118px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-top:var(--wp--preset--spacing--m);margin-bottom:var(--wp--preset--spacing--m)\">Arrivo<\/h2>\n\n\n\n<div class=\"wp-block-group alignwide is-style-alignfull-side-margins has-info-disabled-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-82a81bd3 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--m);margin-bottom:var(--wp--preset--spacing--m);padding-top:var(--wp--preset--spacing--l);padding-bottom:var(--wp--preset--spacing--l)\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\" style=\"margin-top:0;margin-bottom:0\"><img fetchpriority=\"low\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/EC-icon-airplane-blue.svg?w=1024\" alt=\"\" class=\"wp-image-21803\" style=\"width:60px\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-dark-blue-color has-text-color has-link-color content-type-h4 wp-elements-0a7cd96f8417c25564c9df49f2e2c76d wp-block-paragraph\" style=\"border-radius:15px;margin-top:var(--wp--preset--spacing--s);margin-bottom:0;padding-top:0;padding-right:var(--wp--preset--spacing--xs);padding-bottom:0;padding-left:var(--wp--preset--spacing--xs);font-style:normal;font-weight:400\">Arrivo all&#8217;aeroporto<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-pale-color has-alpha-channel-opacity has-primary-pale-background-color has-background is-style-dots\" style=\"margin-top:0;margin-bottom:0\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide mobile-gap-3 mobile-column-gap-3 tablet-gap-5 tablet-column-gap-5 tablet-vertical-alignment-start is-layout-flex wp-container-core-columns-is-layout-185c8862 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--m);padding-right:var(--wp--preset--spacing--l);padding-bottom:var(--wp--preset--spacing--m);padding-left:var(--wp--preset--spacing--l)\">\n<div class=\"wp-block-column is-vertically-aligned-top is-style-sticky-tablet mobile-order-0 text-content is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"margin-top:0;font-style:normal;font-weight:500\">Desidero un trasferimento aeroportuale EC Cambridge, posso arrivare in qualsiasi momento?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se hai prenotato un alloggio con EC, devi arrivare in aeroporto tra le 08:00 e le 20:00. A chi arriva in ritardo o in anticipo potrebbe essere richiesto di prenotare una sistemazione alternativa.<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\">Quali informazioni devo fornire per prenotare un trasferimento aeroportuale?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si prega di fornire il numero del volo, l&#8217;orario di arrivo, il terminal e l&#8217;aeroporto di partenza, con almeno 2 settimane di anticipo.<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\">Chi incontrer\u00f2 in aeroporto?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incontrerai un rappresentante di EC Transport con un cartello con il logo EC e il tuo nome. Ti aspetter\u00e0 agli Arrivi.<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\">Cosa devo fare se non riesco a trovare il rappresentante di EC?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se dopo 10 minuti non vedi il rappresentante di EC, chiama il numero +44 (0)7342037743 (dal banco informazioni o da un telefono cellulare).<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-style-sticky-tablet mobile-order--1 is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-large-font-size wp-block-paragraph\">Cosa devo fare se ho perso il volo o il mio volo \u00e8 in ritardo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dovresti avvisare l&#8217;EC chiamando il numero +44 (0)7342037743 (dallo sportello informazioni o da un telefono cellulare) per modificare l&#8217;orario del tuo trasferimento ed evitare costi aggiuntivi. <\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\">Cosa devo fare se non ho prenotato un trasferimento EC Cambridge?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">National Express e National Rail possono essere prenotati direttamente in aeroporto. Potete rivolgervi agli sportelli dedicati, all&#8217;Information Desk o direttamente online: National Rail <a href=\"https:\/\/www.nationalrail.co.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nationalrail.co.uk<\/a> and National Express <a href=\"https:\/\/www.nationalexpress.com\/en\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nationalexpress.com\/en<\/a> \u2013 cliccate sui link per informazioni sui prezzi.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-warning-disabled-color has-alpha-channel-opacity has-warning-disabled-background-color has-background is-style-dots\" style=\"margin-top:0;margin-bottom:0\"\/>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide is-style-alignfull-side-margins has-pale-beige-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-82a81bd3 wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--m);margin-bottom:var(--wp--preset--spacing--m);padding-top:var(--wp--preset--spacing--l);padding-bottom:var(--wp--preset--spacing--l)\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\" style=\"margin-top:0;margin-bottom:0\"><img fetchpriority=\"low\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/02\/sofa.svg?w=1024\" alt=\"\" class=\"wp-image-10816\" style=\"width:60px\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-rich-black-color has-text-color has-link-color content-type-h4 wp-elements-8cdb9879042d56ae28156ca3cdc7e973 wp-block-paragraph\" style=\"border-radius:15px;margin-top:var(--wp--preset--spacing--s);margin-bottom:0;padding-top:0;padding-right:var(--wp--preset--spacing--xs);padding-bottom:0;padding-left:var(--wp--preset--spacing--xs);font-style:normal;font-weight:400\">Arrivo all&#8217;alloggio EC<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-primary-pale-color has-alpha-channel-opacity has-primary-pale-background-color has-background is-style-dots\" style=\"margin-top:0;margin-bottom:0\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide mobile-gap-3 mobile-column-gap-3 tablet-gap-5 tablet-column-gap-5 tablet-vertical-alignment-start is-layout-flex wp-container-core-columns-is-layout-185c8862 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--m);padding-right:var(--wp--preset--spacing--l);padding-bottom:var(--wp--preset--spacing--m);padding-left:var(--wp--preset--spacing--l)\">\n<div class=\"wp-block-column is-vertically-aligned-top is-style-sticky-tablet mobile-order-0 text-content is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"margin-top:0;font-style:normal;font-weight:500\">Cosa devo aspettarmi dal mio alloggio EC Cambridge?<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\" style=\"margin-top:0\">La famiglia ospitante vi accoglier\u00e0 con un caloroso e personalizzato benvenuto. Tutti i nostri ospiti saranno pienamente informati su come farvi sentire a vostro agio e preparati per il vostro primo giorno di lezione.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-style-sticky-tablet has-border-color has-warm-white-border-color has-ec-white-background-color has-background mobile-order--1 is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:1px;border-radius:15px;padding-top:var(--wp--preset--spacing--l);padding-right:var(--wp--preset--spacing--l);padding-bottom:var(--wp--preset--spacing--l);padding-left:var(--wp--preset--spacing--l)\">\n<figure class=\"wp-block-image size-large is-resized is-style-rounded\"><img fetchpriority=\"low\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/EC-small-icon-special-orange.svg?w=1024\" alt=\"\" class=\"wp-image-21767\" style=\"width:30px\"\/><\/figure>\n\n\n\n<p class=\"has-primary-color has-text-color has-link-color has-small-font-size content-type-h6 wp-elements-537069393690681e104f96070cb20adc wp-block-paragraph\" style=\"font-style:normal;font-weight:700;letter-spacing:1px;text-transform:uppercase\"><strong>Attivit\u00e0 della prima domenica<\/strong><\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"margin-top:0;font-style:normal;font-weight:500\">Cosa dovrei fare la domenica prima dell&#8217;inizio della scuola?<\/p>\n\n\n\n<p style=\"margin-top:0\" class=\"wp-block-paragraph\">Avrai la possibilit\u00e0 di partecipare alle attivit\u00e0 organizzate da EC Cambridge. Questa \u00e8 un&#8217;opportunit\u00e0 per incontrare altri nuovi studenti EC, rilassarti e conoscere la tua nuova citt\u00e0. Con un membro dello staff EC a disposizione, potrai anche porre qualsiasi domanda tu abbia. Ti informeremo sul programma delle attivit\u00e0 domenicali circa 2 settimane prima dell&#8217;inizio della scuola.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-arrow-link\"><a class=\"wp-block-button__link has-medium-font-size has-custom-font-size wp-element-button\" href=\"https:\/\/ecenglish.com\/it\/chi-siamo\/esperienza-tappeto-arancione\/\" style=\"font-style:normal;font-weight:600\">Scopri di pi\u00f9 sulla nostra Orange Carpet Experience\n\t\t\t<div  class=\"arrow-icon-wrap\">\n\t\t\t<svg width=\"8\" height=\"12\" viewBox=\"0 0 8 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t<path d=\"M0.744676 11.2185C0.842471 11.3164 0.958605 11.3941 1.08644 11.4471C1.21427 11.5001 1.35129 11.5273 1.48968 11.5273C1.62806 11.5273 1.76508 11.5001 1.89291 11.4471C2.02075 11.3941 2.13688 11.3164 2.23468 11.2185L6.79168 6.67151C6.8848 6.57862 6.95869 6.46827 7.0091 6.34678C7.05951 6.22529 7.08546 6.09505 7.08546 5.96351C7.08546 5.83198 7.05951 5.70173 7.0091 5.58024C6.95869 5.45875 6.8848 5.3484 6.79168 5.25551L2.23368 0.705511C2.03635 0.50819 1.76873 0.397337 1.48968 0.397337C1.21062 0.397337 0.942996 0.50819 0.745675 0.705511C0.548354 0.902832 0.4375 1.17046 0.4375 1.44951C0.4375 1.72856 0.548354 1.99619 0.745675 2.19351L4.52168 5.96351L0.745675 9.73151C0.647982 9.82912 0.570482 9.94502 0.517606 10.0726C0.46473 10.2002 0.437513 10.3369 0.437513 10.475C0.437513 10.6131 0.46473 10.7499 0.517606 10.8774C0.570482 11.005 0.647982 11.1209 0.745675 11.2185H0.744676Z\" fill=\"#FF712F\"\/>\n\t\t\t<\/svg>\n<\/div>\n\t\t<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--xl);padding-bottom:var(--wp--preset--spacing--xl)\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center mobile-gap-4 mobile-column-gap-4 tablet-gap-5 tablet-column-gap-5 tablet-vertical-alignment-start is-layout-flex wp-container-core-columns-is-layout-4840dda6 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-column is-vertically-aligned-center is-style-sticky-tablet mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.3%\">\n<figure class=\"wp-block-image aligncenter size-full has-custom-border\"><img width=\"720\" height=\"1080\" fetchpriority=\"low\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/01\/Dublin-2-female-students.jpg\" alt=\"\" class=\"wp-image-8298\" style=\"border-radius:1rem\" srcset=\"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Dublin-2-female-students.jpg 720w, https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Dublin-2-female-students-200x300.jpg 200w, https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Dublin-2-female-students-683x1024.jpg 683w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-style-sticky-tablet mobile-order--1 text-content is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Il tuo primo giorno di scuola<\/h2>\n\n\n\n<div class=\"wp-block-columns mobile-gap-3 mobile-column-gap-3 is-layout-flex wp-container-core-columns-is-layout-0666dacc wp-block-columns-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--m)\">\n<div class=\"wp-block-column mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Come posso trovare la strada per la scuola?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi trovare queste informazioni nel tuo profilo di alloggio EC oppure puoi chiedere direttamente ai tuoi host o al personale della residenza.<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Cosa succede se non ho prenotato un alloggio EC Cambridge?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La scuola si trova in Guildhall Place, nel centro citt\u00e0. \u00c8 possibile prendere qualsiasi autobus per il centro e poi attraversare la Grand Arcade (4 minuti) per raggiungere la scuola.<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">A che ora dovrei arrivare?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8:30am.<\/p>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Cosa dovrei portare con me?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 importante portare con s\u00e9 quanto segue il primo giorno:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Passaporto e visto<\/li>\n\n\n\n<li>La tua carta di credito per pagare eventuali spese in sospeso<\/li>\n\n\n\n<li>Lettera di garanzia finanziaria se sei sponsorizzato dal governo<\/li>\n\n\n\n<li>Il tuo quaderno e le tue penne<\/li>\n<\/ul>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Cosa devo fare se il trasporto pubblico \u00e8 temporaneamente non disponibile?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In caso di maltempo, scioperi dei trasporti pubblici, ecc., consultare la pagina <a href=\"https:\/\/www.facebook.com\/ec.cambridge\/\" target=\"_blank\" rel=\"noreferrer noopener\">EC Cambridge Facebook page<\/a> per eventuali aggiornamenti importanti o chiamare il numero di emergenza.<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-error-disabled-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-787142bc wp-block-group-is-layout-constrained\" style=\"border-radius:1rem;padding-top:var(--wp--preset--spacing--m);padding-right:var(--wp--preset--spacing--m);padding-bottom:var(--wp--preset--spacing--m);padding-left:var(--wp--preset--spacing--m)\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Cosa posso aspettarmi il primo giorno?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il tuo primo giorno riceverai la migliore accoglienza possibile nella famiglia EC Cambridge. Goditi l&#8217;attenzione incondizionata del nostro staff in un&#8217;atmosfera rilassata e amichevole. Ecco cosa includer\u00e0 il tuo primo giorno:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Colloquio di orientamento<\/li>\n\n\n\n<li>Valutazione orale<\/li>\n\n\n\n<li>&#8220;Come impariamo&#8221; \u2013 sessione su come avere successo con l&#8217;EC, inclusi i nostri stili e metodi di insegnamento<\/li>\n<\/ul>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Quale sar\u00e0 il mio orario?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Riceverai l&#8217;orario a scuola alle 10:30<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-style-alignfull-side-margins has-info-disabled-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-03cec7fc wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--l);margin-bottom:var(--wp--preset--spacing--l);padding-top:var(--wp--preset--spacing--l);padding-right:var(--wp--preset--spacing--s);padding-bottom:var(--wp--preset--spacing--l);padding-left:var(--wp--preset--spacing--s)\">\n<figure class=\"wp-block-image aligncenter size-large is-resized\" style=\"margin-top:0;margin-bottom:0\"><img fetchpriority=\"low\" decoding=\"async\" loading=\"lazy\" src=\"https:\/\/ecenglish.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/EC-icon-planning-blue.svg?w=1024\" alt=\"\" class=\"wp-image-21771\" style=\"width:60px\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-digital-blue-color has-text-color has-link-color content-type-h4 wp-elements-25741c5d68480a7858b5c7f392d41b21 wp-block-paragraph\" style=\"border-radius:15px;margin-top:var(--wp--preset--spacing--s);margin-bottom:0;padding-top:0;padding-right:var(--wp--preset--spacing--xs);padding-bottom:0;padding-left:var(--wp--preset--spacing--xs);font-style:normal;font-weight:400\">Giorni festivi<\/p>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-container-core-group-is-layout-16c7ee5c wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--s)\">\n<p class=\"has-text-align-center has-large-font-size content-type-p wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Cosa succede nei giorni festivi?<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size content-type-p wp-block-paragraph\">Le scuole non aprono nei giorni festivi, quindi se luned\u00ec \u00e8 un giorno festivo, il primo giorno di scuola sar\u00e0 marted\u00ec.Giorni festivi feriali del 2026: 01 gennaio, 03 aprile, 06 aprile, 04 maggio, 25 maggio, 31 agosto, 25 dicembre, 28 dicembre<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-global-padding is-content-justification-center is-layout-constrained wp-container-core-group-is-layout-c66bcc3a wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--xxl);padding-bottom:var(--wp--preset--spacing--xxl)\">\n<h2 class=\"wp-block-heading has-text-align-left\" style=\"margin-bottom:var(--wp--preset--spacing--m)\">Centre Information<\/h2>\n\n\n\n<div class=\"wp-block-columns alignwide align-items-flex-start columns-school-info-2 mobile-gap-4 mobile-column-gap-2 tablet-gap-5 tablet-column-gap-3 tablet-vertical-alignment-start mobile-gap-3 mobile-column-gap-3 is-layout-flex wp-container-core-columns-is-layout-1e36e224 wp-block-columns-is-layout-flex\" style=\"padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-column is-vertically-aligned-top align-self-start is-style-default col-info mobile-order--1 text-content is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:34%\">\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">EC Cambridge<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3 Guildhall Chambers, Guildhall Place, <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cambridge CB2 3AE, UK<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\" style=\"margin-top:var(--wp--preset--spacing--s)\">\n<div class=\"wp-block-button is-style-tertiary\"><a class=\"wp-block-button__link has-digital-blue-color has-text-color has-link-color wp-element-button\" href=\"https:\/\/maps.app.goo.gl\/4VEWMKawmYSDzm969\" target=\"_blank\" rel=\"noreferrer noopener\">Vedi Dentro<svg width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M11.793 5.7928C11.7001 5.88559 11.6263 5.99579 11.576 6.11711C11.5257 6.23842 11.4998 6.36846 11.4998 6.4998C11.4998 6.63113 11.5257 6.76118 11.576 6.88249C11.6263 7.00381 11.7001 7.11401 11.793 7.2068L15.586 10.9998H6C5.73478 10.9998 5.48043 11.1052 5.29289 11.2927C5.10536 11.4802 5 11.7346 5 11.9998C5 12.265 5.10536 12.5194 5.29289 12.7069C5.48043 12.8944 5.73478 12.9998 6 12.9998H15.586L11.793 16.7928C11.7001 16.8856 11.6263 16.9958 11.576 17.1171C11.5257 17.2384 11.4998 17.3685 11.4998 17.4998C11.4998 17.6311 11.5257 17.7612 11.576 17.8825C11.6263 18.0038 11.7001 18.114 11.793 18.2068C12.183 18.5968 12.817 18.5968 13.208 18.2068L18.707 12.7068C18.8881 12.5264 18.993 12.2833 19 12.0278V11.9708C18.9928 11.7156 18.888 11.4729 18.707 11.2928L13.208 5.7928C13.1151 5.69982 13.0048 5.62606 12.8834 5.57574C12.762 5.52541 12.6319 5.49951 12.5005 5.49951C12.3691 5.49951 12.239 5.52541 12.1176 5.57574C11.9962 5.62606 11.8859 5.69982 11.793 5.7928Z\" fill=\"currentColor\"\/><\/svg><\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-ec-grey-4-color has-alpha-channel-opacity has-ec-grey-4-background-color has-background is-style-dots\"\/>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\" style=\"margin-top:var(--wp--preset--spacing--s);margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<p class=\"wp-block-paragraph\"><strong>Numero di telefono:<\/strong>&nbsp;&nbsp;<a href=\"tel:+44 (0)1223 464364\">+44 (0)1223 464364<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Numero di emergenza:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(Da utilizzare solo al di fuori dell&#8217;orario d&#8217;ufficio)<a href=\"tel:+1 424 428 8866\"><\/a><a href=\"tel:+44 (0)7342037743\">+44 (0)7342037743<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top align-self-start is-style-default col-working-hours mobile-order--1 text-content is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:25%\">\n<h4 class=\"wp-block-heading has-large-font-size\" style=\"margin-bottom:var(--wp--preset--spacing--m);font-style:normal;font-weight:500\">Orari di apertura<\/h4>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile mobile-gap-3 mobile-column-gap-3 is-layout-flex wp-container-core-columns-is-layout-e3eb1968 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0\">\n<div class=\"wp-block-column mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:110px\">\n<p class=\"wp-block-paragraph\">Luned\u00ec<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marted\u00ec<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mercoled\u00ec<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gioved\u00ec<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venerd\u00ec<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabato<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Domenica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Orari d&#8217;ufficio<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">08:30 \u2013 17:00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">08:30 \u2013 17:00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">08:30 \u2013 17:00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">08:30 \u2013 17:00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">08:30 \u2013 17:00<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chiuso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chiuso<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">8:30 \u2013 17:00<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top align-self-start is-style-default col-map mobile-order-0 is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:42%\">\n<h4 class=\"wp-block-heading has-large-font-size\" style=\"margin-bottom:var(--wp--preset--spacing--m);font-style:normal;font-weight:500\">Mappa<\/h4>\n\n\n\n<div class=\"wp-block-ec-google-map-iframe\">\n\t<div class=\"iframe-wrapper\" style=\"aspect-ratio: 552\/370\">\n\t\t<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d4890.279591899917!2d0.119895!3d52.204507!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x47d870aee097995d%3A0xb215616f962bfe52!2sEC%20Cambridge%20English%20Language%20School!5e0!3m2!1sen!2sus!4v1744197661016!5m2!1sen!2sus\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>\t\t\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull overflow-hidden has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--m);padding-bottom:var(--wp--preset--spacing--m)\">\n<div class=\"wp-block-group alignwide is-layout-flow wp-block-group-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\" style=\"margin-top:0;margin-bottom:var(--wp--preset--spacing--s)\">Orario<\/h2>\n\n\n\n<p class=\"has-text-align-center has-large-font-size content-type-p wp-block-paragraph\" style=\"font-style:normal;font-weight:500\">Quale sar\u00e0 il mio orario?<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Questo \u00e8 un orario di esempio, gli orari potrebbero cambiare e non sono garantiti.<\/p>\n\n\n\n\n\n<div style=\"margin-top:var(--wp--preset--spacing--s)\" class=\"wp-block-ec-tabs alignfull\">\n\t<div class=\"tabs-container\">\n\t\t<div class=\"tabs-head swiper tabs-slider\">\n\t\t\t<ul class=\"swiper-wrapper tabs-head__list\" data-color-scheme=\"dark\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li\n\t\t\t\t\t\trole=\"button\"\n\t\t\t\t\t\tdata-tab=\" Esempio di orario\"\n\t\t\t\t\t\tclass=\"swiper-slide tabs-head__list-item active\"\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"caption\">\n\t\t\t\t\t\t\t Esempio di orario\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"tabs-body\">\n\t\t\n\n\n\n\n\n<div class=\"wp-block-ec-tab active\" data-tab=\" Esempio di orario\">\n\t<div class=\"tab-content\">\n\t\t\n<div class=\"tablepress-table-wrapper\">\n<table id=\"tablepress-40\" class=\"tablepress tablepress-id-40 tbody-has-connected-cells\">\n<thead>\n<tr class=\"row-1\">\n\t<td class=\"column-1\"><\/td><th class=\"column-2\">Monday<\/th><th class=\"column-3\">Tuesday<\/th><th class=\"column-4\">Wednesday<\/th><th class=\"column-5\">Thursday<\/th><th class=\"column-6\">Friday<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">9:00 &#8211; 10:30<\/td><td class=\"column-2\">Core Class A<\/td><td class=\"column-3\">Core Class B<\/td><td class=\"column-4\">Core Class A<\/td><td class=\"column-5\">Core Class B<\/td><td class=\"column-6\">Core Class A<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">10:30 &#8211; 10:45<\/td><td colspan=\"5\" class=\"column-2\">Break<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">10:45 &#8211; 12:15<\/td><td class=\"column-2\">Core Class A<\/td><td class=\"column-3\">Core Class B<\/td><td class=\"column-4\">Core Class A<\/td><td class=\"column-5\">Core Class B<\/td><td class=\"column-6\">Core Class A<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">12:15 &#8211; 13:00<\/td><td colspan=\"5\" class=\"column-2\">Lunch Break<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">13:00 &#8211; 14:30<\/td><td colspan=\"5\" class=\"column-2\">Special Focus Classes<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">14:30 &#8211; 14:45<\/td><td colspan=\"5\" class=\"column-2\">Break<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">14:45 &#8211; 16:15<\/td><td class=\"column-2\">Core Class B<\/td><td class=\"column-3\">Core Class A<\/td><td class=\"column-4\">Core Class B<\/td><td class=\"column-5\">Core Class A<\/td><td class=\"column-6\">Core Class B<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">16:15 &#8211; 16:30<\/td><td colspan=\"5\" class=\"column-2\">Break<\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">16:30 &#8211; 18:00<\/td><td class=\"column-2\">Core Class B<\/td><td class=\"column-3\">Core Class A<\/td><td class=\"column-4\">Core Class B<\/td><td class=\"column-5\">Core Class A<\/td><td class=\"column-6\">Core Class B<\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">After school<\/td><td colspan=\"5\" class=\"column-2\">Language activities &amp; social events\/ free time\/ study time<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div><!-- #tablepress-40 from cache -->\n\t<\/div>\n<\/div>\n\n\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"ec-anchor-navigation-stop\"><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-warm-white-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--xl);margin-bottom:1.25rem;padding-top:var(--wp--preset--spacing--xl);padding-bottom:var(--wp--preset--spacing--xl)\">\n<h3 class=\"wp-block-heading has-text-align-center\">Lasciati ispirare dai viaggi dei nostri studenti<\/h3>\n\n\n\n<p class=\"has-text-align-center has-large-font-size content-type-p wp-block-paragraph\">Scoprite come i nostri studenti hanno trasformato i loro primi passi nell&#8217;apprendimento delle lingue in pietre miliari che hanno trasformato la loro vita. Lasciate che le loro storie vi ispirino a raggiungere il vostro successo linguistico.<\/p>\n\n\n\n<div style=\"margin-top:var(--wp--preset--spacing--l)\" class=\"testimonial-video alignwide wp-block-ec-video-testimonials\">\n\t\n\t<a href=\"https:\/\/vimeo.com\/1052204255\/b7486a8787\" data-fancybox=\"fancy_6a9868adb27cf\"\n\t\tclass=\"testimonial-video__item active\"\n\t\tstyle=\"background-image: url('https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/02\/EC-Cambridge-Rayan-testimonial-crop.jpg'); background-position: 50% top;\">\n\t\t<div class=\"testimonial-video__item__play\">\n\t\t\t<svg width=\"60\" height=\"61\" viewBox=\"0 0 60 61\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle opacity=\"0.9\" cx=\"30\" cy=\"30.5293\" r=\"30\" fill=\"white\"\/>\n\t\t\t\t<path\n\t\t\t\t\td=\"M41.4467 28.2425C42.9153 28.981 42.9153 31.0776 41.4467 31.8161L24.6485 40.2631C23.3184 40.9319 21.75 39.9651 21.75 38.4763V21.5823C21.75 20.0935 23.3184 19.1266 24.6485 19.7955L41.4467 28.2425Z\"\n\t\t\t\t\tfill=\"#11161C\"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<div class=\"testimonial-video__item__content\">\n\t\t\t<h4>Rayan, Saudi Arabia<\/h4>\n\t\t\t<p><\/p>\n\t\t<\/div>\n\t<\/a>\n\n\t<a href=\"https:\/\/vimeo.com\/1026502228\/9b5403dd51\" data-fancybox=\"fancy_6a9868adb27cf\"\n\t\tclass=\"testimonial-video__item \"\n\t\tstyle=\"background-image: url('https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/02\/Study-at-EC-London-Elena-from-Russia-crop.jpg'); background-position: 30% top;\">\n\t\t<div class=\"testimonial-video__item__play\">\n\t\t\t<svg width=\"60\" height=\"61\" viewBox=\"0 0 60 61\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle opacity=\"0.9\" cx=\"30\" cy=\"30.5293\" r=\"30\" fill=\"white\"\/>\n\t\t\t\t<path\n\t\t\t\t\td=\"M41.4467 28.2425C42.9153 28.981 42.9153 31.0776 41.4467 31.8161L24.6485 40.2631C23.3184 40.9319 21.75 39.9651 21.75 38.4763V21.5823C21.75 20.0935 23.3184 19.1266 24.6485 19.7955L41.4467 28.2425Z\"\n\t\t\t\t\tfill=\"#11161C\"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<div class=\"testimonial-video__item__content\">\n\t\t\t<h4>Elena, Russia<\/h4>\n\t\t\t<p><\/p>\n\t\t<\/div>\n\t<\/a>\n\n\t<a href=\"https:\/\/vimeo.com\/1024400040\/7553a3289e\" data-fancybox=\"fancy_6a9868adb27cf\"\n\t\tclass=\"testimonial-video__item \"\n\t\tstyle=\"background-image: url('https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/02\/Learn-English-at-EC-Malta-30-Nicolas-cropped.jpg'); background-position: 50% top;\">\n\t\t<div class=\"testimonial-video__item__play\">\n\t\t\t<svg width=\"60\" height=\"61\" viewBox=\"0 0 60 61\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle opacity=\"0.9\" cx=\"30\" cy=\"30.5293\" r=\"30\" fill=\"white\"\/>\n\t\t\t\t<path\n\t\t\t\t\td=\"M41.4467 28.2425C42.9153 28.981 42.9153 31.0776 41.4467 31.8161L24.6485 40.2631C23.3184 40.9319 21.75 39.9651 21.75 38.4763V21.5823C21.75 20.0935 23.3184 19.1266 24.6485 19.7955L41.4467 28.2425Z\"\n\t\t\t\t\tfill=\"#11161C\"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<div class=\"testimonial-video__item__content\">\n\t\t\t<h4>Nicolas, Colombia<\/h4>\n\t\t\t<p><\/p>\n\t\t<\/div>\n\t<\/a>\n\n\t<a href=\"https:\/\/vimeo.com\/1026135625\/dde3a1bf72\" data-fancybox=\"fancy_6a9868adb27cf\"\n\t\tclass=\"testimonial-video__item \"\n\t\tstyle=\"background-image: url('https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/02\/Yunseop-Korea-crop.jpg'); background-position: 50% top;\">\n\t\t<div class=\"testimonial-video__item__play\">\n\t\t\t<svg width=\"60\" height=\"61\" viewBox=\"0 0 60 61\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<circle opacity=\"0.9\" cx=\"30\" cy=\"30.5293\" r=\"30\" fill=\"white\"\/>\n\t\t\t\t<path\n\t\t\t\t\td=\"M41.4467 28.2425C42.9153 28.981 42.9153 31.0776 41.4467 31.8161L24.6485 40.2631C23.3184 40.9319 21.75 39.9651 21.75 38.4763V21.5823C21.75 20.0935 23.3184 19.1266 24.6485 19.7955L41.4467 28.2425Z\"\n\t\t\t\t\tfill=\"#11161C\"\/>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<div class=\"testimonial-video__item__content\">\n\t\t\t<h4>Yunseop, Korea<\/h4>\n\t\t\t<p><\/p>\n\t\t<\/div>\n\t<\/a>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Preparati per la tua esperienza EC Cambridge Informazioni essenziali per prepararsi al viaggio a Cambridge Arrivo Arrivo all&#8217;aeroporto Desidero un<\/p>\n","protected":false},"author":9,"featured_media":4746,"parent":2031,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false,"footnotes":""},"page_category":[70],"activity_category":[],"activity_location":[],"course_category":[],"destination_age_group":[],"destination_category":[],"lesson_category":[],"class_list":["post-2253","page","type-page","status-publish","has-post-thumbnail","hentry","page_category-travel-activities"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cambridge Pre-Arrivo al Primo Giorno - EC<\/title>\n<meta name=\"description\" content=\"Scopri tutto ci\u00f2 che devi sapere per una transizione senza intoppi all&#039;apprendimento dell&#039;inglese a Cambridge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cambridge Pre-Arrivo al Primo Giorno - EC\" \/>\n<meta property=\"og:description\" content=\"Scopri tutto ci\u00f2 che devi sapere per una transizione senza intoppi all&#039;apprendimento dell&#039;inglese a Cambridge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/\" \/>\n<meta property=\"og:site_name\" content=\"EC English ( IT )\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-24T14:15:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Punting-Tour-with-friends-in-Cambridge.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/\",\"url\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/\",\"name\":\"Cambridge Pre-Arrivo al Primo Giorno - EC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/Punting-Tour-with-friends-in-Cambridge.jpg\",\"datePublished\":\"2025-01-14T09:02:29+00:00\",\"dateModified\":\"2026-07-24T14:15:10+00:00\",\"description\":\"Scopri tutto ci\u00f2 che devi sapere per una transizione senza intoppi all'apprendimento dell'inglese a Cambridge.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/Punting-Tour-with-friends-in-Cambridge.jpg\",\"contentUrl\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/01\\\/Punting-Tour-with-friends-in-Cambridge.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"EC Cambridge Destination 2014\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/ec-cambridge-arrivo-primo-giorno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scuole di lingua inglese all&#8217;estero \u00a0\u00a0\",\"item\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Impara l&#8217;inglese nel Regno Unito\",\"item\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/scuole\\\/inghilterra\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"EC Cambridge arrivo primo giorno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/\",\"name\":\"EC English\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ecenglish.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cambridge Pre-Arrivo al Primo Giorno - EC","description":"Scopri tutto ci\u00f2 che devi sapere per una transizione senza intoppi all'apprendimento dell'inglese a Cambridge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/","og_locale":"en_US","og_type":"article","og_title":"Cambridge Pre-Arrivo al Primo Giorno - EC","og_description":"Scopri tutto ci\u00f2 che devi sapere per una transizione senza intoppi all'apprendimento dell'inglese a Cambridge.","og_url":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/","og_site_name":"EC English ( IT )","article_modified_time":"2026-07-24T14:15:10+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Punting-Tour-with-friends-in-Cambridge.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/","url":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/","name":"Cambridge Pre-Arrivo al Primo Giorno - EC","isPartOf":{"@id":"https:\/\/ecenglish.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/#primaryimage"},"image":{"@id":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/#primaryimage"},"thumbnailUrl":"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Punting-Tour-with-friends-in-Cambridge.jpg","datePublished":"2025-01-14T09:02:29+00:00","dateModified":"2026-07-24T14:15:10+00:00","description":"Scopri tutto ci\u00f2 che devi sapere per una transizione senza intoppi all'apprendimento dell'inglese a Cambridge.","breadcrumb":{"@id":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/#primaryimage","url":"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Punting-Tour-with-friends-in-Cambridge.jpg","contentUrl":"https:\/\/ecenglish.com\/it\/wp-content\/uploads\/sites\/5\/2025\/01\/Punting-Tour-with-friends-in-Cambridge.jpg","width":1620,"height":1080,"caption":"EC Cambridge Destination 2014"},{"@type":"BreadcrumbList","@id":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/ec-cambridge-arrivo-primo-giorno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ecenglish.com\/it\/"},{"@type":"ListItem","position":2,"name":"Scuole di lingua inglese all&#8217;estero \u00a0\u00a0","item":"https:\/\/ecenglish.com\/it\/scuole\/"},{"@type":"ListItem","position":3,"name":"Impara l&#8217;inglese nel Regno Unito","item":"https:\/\/ecenglish.com\/it\/scuole\/inghilterra\/"},{"@type":"ListItem","position":4,"name":"EC Cambridge arrivo primo giorno"}]},{"@type":"WebSite","@id":"https:\/\/ecenglish.com\/it\/#website","url":"https:\/\/ecenglish.com\/it\/","name":"EC English","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ecenglish.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/pages\/2253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/comments?post=2253"}],"version-history":[{"count":17,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/pages\/2253\/revisions"}],"predecessor-version":[{"id":19329,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/pages\/2253\/revisions\/19329"}],"up":[{"embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/pages\/2031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/media\/4746"}],"wp:attachment":[{"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/media?parent=2253"}],"wp:term":[{"taxonomy":"page_category","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/page_category?post=2253"},{"taxonomy":"activity_category","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/activity_category?post=2253"},{"taxonomy":"activity_location","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/activity_location?post=2253"},{"taxonomy":"course_category","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/course_category?post=2253"},{"taxonomy":"destination_age_group","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/destination_age_group?post=2253"},{"taxonomy":"destination_category","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/destination_category?post=2253"},{"taxonomy":"lesson_category","embeddable":true,"href":"https:\/\/ecenglish.com\/it\/wp-json\/wp\/v2\/lesson_category?post=2253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}